{"id":139485,"date":"2018-09-25T13:34:57","date_gmt":"2018-09-25T11:34:57","guid":{"rendered":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=139485"},"modified":"2018-09-25T13:34:57","modified_gmt":"2018-09-25T11:34:57","slug":"polizei-ermittelt-im-hambacher-forst-gegen-die-mutter-eines-sechsjaehrigen-dieser-war-vermummt","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/polizei-ermittelt-im-hambacher-forst-gegen-die-mutter-eines-sechsjaehrigen-dieser-war-vermummt\/","title":{"rendered":"Polizei ermittelt im Hambacher Forst gegen die Mutter eines Sechsj\u00e4hrigen &#8211; dieser war vermummt"},"content":{"rendered":"<blockquote class=\"twitter-tweet\" data-lang=\"en\">\n<p lang=\"de\" dir=\"ltr\">Ehu Duisburg (wer sonst?) f\u00fchrt Personalienfeststellung durch, weil sich 6j\u00e4hriger mit Schal vermummt habe  Kein Scherz!<a href=\"https:\/\/twitter.com\/hashtag\/HambacherForst?src=hash&amp;ref_src=twsrc%5Etfw\">#HambacherForst<\/a> <a href=\"https:\/\/t.co\/rop63nREom\">pic.twitter.com\/rop63nREom<\/a><\/p>\n<p>&mdash; Theo Heyen (@FeinwerkCGN) <a href=\"https:\/\/twitter.com\/FeinwerkCGN\/status\/1044253177896464384?ref_src=twsrc%5Etfw\">September 24, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Sternstunden der Polizeiarbeit im Hambacher Forst. Twitter-Userin <a href=\"https:\/\/twitter.com\/F4y3M14\">Barfu\u00dfmama<\/a> ist mit ihrem 6-j\u00e4hrigen Sohn und der 15-j\u00e4hrigen Tochter von Berlin aus in den Hambacher Forst gereist, um sich ein Bild von dem zu machen, was dort vor sich geht.<\/p>\n<blockquote class=\"twitter-tweet\" data-conversation=\"none\" data-lang=\"en\">\n<p lang=\"de\" dir=\"ltr\">Ich bin die Mutter des 6 j\u00e4hrigen. Es wurden meine Personalien und die meines 6 j\u00e4hrigen aufgenommen. Ich bekomme die Anzeigen wegen der angeblichen vermummung meines Sohnes und dem Jugendamt wird auch ein Bericht geschickt. Es ist wahr u real.<\/p>\n<p>&mdash; Barfu\u00dfmama (@F4y3M14) <a href=\"https:\/\/twitter.com\/F4y3M14\/status\/1044449551401275392?ref_src=twsrc%5Etfw\">September 25, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Ihr Bursche hatte sich dort dann wohl ein Tuch vors Gesicht gezogen. Auf dem R\u00fcckweg wurde die Familie dann von der Polizei aufgehalten. <\/p>\n<blockquote class=\"twitter-tweet\" data-conversation=\"none\" data-lang=\"en\">\n<p lang=\"de\" dir=\"ltr\">Als wir nach Hause wollten haben uns 8 Polizisten angehalten. Wollten meinen Ausweis und Name ect. von meinem Sohn. Auf Nachfrage wieso wurde uns mitgeteilt das gegen mich als Mutter ermittelt wird weil mein Sohn mehrfach gegen das Vermummungsgesetz (1)<\/p>\n<p>&mdash; Barfu\u00dfmama (@F4y3M14) <a href=\"https:\/\/twitter.com\/F4y3M14\/status\/1044491713203589121?ref_src=twsrc%5Etfw\">September 25, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-conversation=\"none\" data-lang=\"en\">\n<p lang=\"de\" dir=\"ltr\">hat. Der Polizist sagte sie h\u00e4tten Filmmaterial von verschiedenen Tagen an denen er zeitweise den Schal vor dem Gesicht hatte. Ich war \u00fcbrigens immer unvermmumt neben ihm. Deshalb hab ich gefragt wieso sie mich nicht einfach angesprochen haben. (2)<\/p>\n<p>&mdash; Barfu\u00dfmama (@F4y3M14) <a href=\"https:\/\/twitter.com\/F4y3M14\/status\/1044492508779237376?ref_src=twsrc%5Etfw\">September 25, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Die Polizei hat die Anzeige wohl auch beim Jugendamt gemeldet. <\/p>\n<blockquote class=\"twitter-tweet\" data-conversation=\"none\" data-lang=\"en\">\n<p lang=\"de\" dir=\"ltr\">Der Polizist meinte ich als Mutter und Aufsichtsperson vor Ort w\u00e4re sozusagen haftbar zu machen. Des weiteren wird die Polizei eine Anzeige\/Bericht ans Jugendamt schicken. Keine Ahnung ob ich strafrechtlich verfolgt werde bzw. werden kann&#8230;denke das erfahre ich die Tage<\/p>\n<p>&mdash; Barfu\u00dfmama (@F4y3M14) <a href=\"https:\/\/twitter.com\/F4y3M14\/status\/1044455050213494784?ref_src=twsrc%5Etfw\">September 25, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Barfu\u00dfmama schreibt auch, dass sie immer nur dort im Wald war, wo ihr das von der Polizei genehmigt wurde und das sie im Pressebereich war, um ihre gro\u00dfe Tochter nicht alleine zu lassen, die dort f\u00fcr die Sch\u00fclerzeitung recherchierte. <\/p>\n<p>Und dabei wollte der Kleine halt nur ein bisschen Spa\u00df im Wald haben. Und machte das, was jene machen, von denen er mal einer werden will, halt so machen. <\/p>\n<blockquote class=\"twitter-tweet\" data-conversation=\"none\" data-lang=\"en\">\n<p lang=\"de\" dir=\"ltr\">Da die Polizei meinen Sohn ja sowieso 3 Tage zur Beweissicherung (heimlich) gefilmt hat (Aussage des Polizisten) kann ich ja hier zeigen wie mein Sohn gespielt hat. Er will \u00fcbrigens SEK-Mann werden \ud83d\ude02 <a href=\"https:\/\/t.co\/1BYJd8TEAf\">pic.twitter.com\/1BYJd8TEAf<\/a><\/p>\n<p>&mdash; Barfu\u00dfmama (@F4y3M14) <a href=\"https:\/\/twitter.com\/F4y3M14\/status\/1044490694910447616?ref_src=twsrc%5Etfw\">September 25, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ehu Duisburg (wer sonst?) f\u00fchrt Personalienfeststellung durch, weil sich 6j\u00e4hriger mit Schal vermummt habe Kein Scherz!#HambacherForst pic.twitter.com\/rop63nREom &mdash; Theo Heyen (@FeinwerkCGN) September 24, 2018 Sternstunden&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/polizei-ermittelt-im-hambacher-forst-gegen-die-mutter-eines-sechsjaehrigen-dieser-war-vermummt\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Polizei ermittelt im Hambacher Forst gegen die Mutter eines Sechsj\u00e4hrigen &#8211; dieser war vermummt<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":139487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[7054,1956,215],"class_list":["post-139485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nur-mal-so","tag-hambacherforst","tag-childs","tag-cops","entry"],"jetpack_featured_media_url":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2018\/09\/Bildschirmfoto-2018-09-25-um-13.32.18.jpg","jetpack_shortlink":"https:\/\/wp.me\/pXEnA-AhL","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/139485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=139485"}],"version-history":[{"count":4,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/139485\/revisions"}],"predecessor-version":[{"id":139490,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/139485\/revisions\/139490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media\/139487"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=139485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=139485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=139485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}