{"id":172759,"date":"2021-09-14T21:04:28","date_gmt":"2021-09-14T19:04:28","guid":{"rendered":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=172759"},"modified":"2021-09-14T21:05:11","modified_gmt":"2021-09-14T19:05:11","slug":"hans-georg-maassen-ein-gastwirt-die-presse-und-ein-neo-nazi","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/hans-georg-maassen-ein-gastwirt-die-presse-und-ein-neo-nazi\/","title":{"rendered":"Hans-Georg Maa\u00dfen, ein Gastwirt, die Presse und ein Neo-Nazi"},"content":{"rendered":"<p>Die CDU macht sich stark f\u00fcr Leute wie den ehemaligen Verfassungsschutzchef Hans-Georg Maa\u00dfen, der jetzt bitte mal in Ruhe essen m\u00f6chte. Ist ihm egal, dass da Nazis mit am Start sind, die mittlerweile empfehlen, Maa\u00dfen zu w\u00e4hlen. Die CDU\/CSU toleriert das. Oder hofiert das gar. Die CDU &#8222;warnt&#8220; vor einem &#8222;Linksruck&#8220;. K\u00f6nnte ich diesen dann bitte jetzt endlich mal sehen? <\/p>\n<p>https:\/\/twitter.com\/SPIEGELTV\/status\/1437753764933406722<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">\u27a1\ufe0fHans-Peter Friedrich (CSU) machte ihn zum Pr\u00e4sidenten des <a href=\"https:\/\/twitter.com\/BfV_Bund?ref_src=twsrc%5Etfw\">@BfV_Bund<\/a> <br \/>\u27a1\ufe0fHorst Seehofer (CSU) st\u00fctzte ihn bis zum Ende<br \/>\u27a1\ufe0fWolfgang Sch\u00e4uble (CDU) nennt ihn einen Demokraten<br \/>\u27a1\ufe0fJens Spahn (CDU) findet, man sollte ihn w\u00e4hlen<br \/>\u27a1\ufe0fArmin Laschet &amp; Paul Ziemiak (CDU) lassen ihn gew\u00e4hren <a href=\"https:\/\/t.co\/mSnOunD7CC\">https:\/\/t.co\/mSnOunD7CC<\/a><\/p>\n<p>&mdash; Ren\u00e9 Engel (@Engel_Re) <a href=\"https:\/\/twitter.com\/Engel_Re\/status\/1437775106688884739?ref_src=twsrc%5Etfw\">September 14, 2021<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die CDU macht sich stark f\u00fcr Leute wie den ehemaligen Verfassungsschutzchef Hans-Georg Maa\u00dfen, der jetzt bitte mal in Ruhe essen m\u00f6chte. Ist ihm egal, dass&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/hans-georg-maassen-ein-gastwirt-die-presse-und-ein-neo-nazi\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Hans-Georg Maa\u00dfen, ein Gastwirt, die Presse und ein Neo-Nazi<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":172760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[4762,447],"class_list":["post-172759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alltaglicher-sinnwahn","tag-maassen","tag-nazis","entry"],"jetpack_featured_media_url":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2021\/09\/Bildschirmfoto-2021-09-14-um-21.00.56.jpg","jetpack_shortlink":"https:\/\/wp.me\/pXEnA-IWr","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/172759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=172759"}],"version-history":[{"count":3,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/172759\/revisions"}],"predecessor-version":[{"id":172762,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/172759\/revisions\/172762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media\/172760"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=172759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=172759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=172759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}