{"id":1977,"date":"2006-08-30T16:14:00","date_gmt":"2006-08-30T15:14:00","guid":{"rendered":"http:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=1977"},"modified":"2006-08-30T16:14:00","modified_gmt":"2006-08-30T15:14:00","slug":"mit-alten-platten","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/mit-alten-platten\/","title":{"rendered":"Mit alten Platten"},"content":{"rendered":"<div align=\"justify\">ist das ja auch immer so eine Sache. Es gibt manche, die h\u00f6rt man immer noch ziemlich regelm\u00e4\u00dfig, andere eher selten und die ganz harten F\u00e4lle versteck man am besten ganz weit hinten im Regal oder,- noch besser &#8211; unterm Bett. Sollte die dann doch mal jemand eher zuf\u00e4llig entdecken, sagt man einfach, &#8222;die sind von meinem Bruder&#8220; oder &#8222;die habe ich mal von Mutti zum Geburtstag bekommen&#8220;. Wenn ich mir meine alten Platten so ansehe, m\u00fcssen so einige von meinem Bruder, oder eben meiner Mutter sein. Allerdings sind da dann auch doch so feine Sachen bei, die ich mir heute Morgen mal ganz klassisch auf meinen Player kopiert habe. Und nun fahr ich durch die Gegend und hab <a href=\"http:\/\/www.amazon.de\/Es-Ist-Egal-Aber\/dp\/B000025OL6\/sr=1-1\/qid=1156951081\/ref=sr_1_1\/028-9329399-7849305?ie=UTF8&amp;s=music\">die Platte<\/a> in den Ohren, die ich noch in meinen etwas j\u00fcngeren Tagen so mochte. Und irgendwie mag ich die heute auch noch. Was wohl Mutti dazu sgane w\u00fcrde?<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ist das ja auch immer so eine Sache. Es gibt manche, die h\u00f6rt man immer noch ziemlich regelm\u00e4\u00dfig, andere eher selten und die ganz harten&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/mit-alten-platten\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Mit alten Platten<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1977","post","type-post","status-publish","format-standard","hentry","category-nur-mal-so","entry"],"jetpack_shortlink":"https:\/\/wp.me\/pXEnA-vT","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/1977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=1977"}],"version-history":[{"count":0,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/1977\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=1977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=1977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=1977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}