{"id":197906,"date":"2024-03-14T15:30:43","date_gmt":"2024-03-14T14:30:43","guid":{"rendered":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=197906"},"modified":"2024-03-14T15:30:43","modified_gmt":"2024-03-14T14:30:43","slug":"in-new-orleans-fressen-ratten-konfisziertes-marihuana-in-marodem-polizeipraesidium","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/in-new-orleans-fressen-ratten-konfisziertes-marihuana-in-marodem-polizeipraesidium\/","title":{"rendered":"In New Orleans fressen Ratten konfisziertes Marihuana in marodem Polizeipr\u00e4sidium"},"content":{"rendered":"<figure id=\"attachment_197908\" aria-describedby=\"caption-attachment-197908\" style=\"width: 1280px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2024\/03\/rat-4075129_1280.jpg\" alt=\"\" width=\"1280\" height=\"687\" class=\"size-full wp-image-197908\" srcset=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2024\/03\/rat-4075129_1280.jpg 1280w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2024\/03\/rat-4075129_1280-300x161.jpg 300w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2024\/03\/rat-4075129_1280-600x322.jpg 600w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2024\/03\/rat-4075129_1280-768x412.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-197908\" class=\"wp-caption-text\"><small>(Foto: <a href=\"https:\/\/pixabay.com\/de\/photos\/ratten-farbratten-nagetier-fell-4075129\/\">sipa<\/a>)<\/small><br \/><\/figcaption><\/figure>\n<p>Wir alle kennen die Jokes von den Mengen durch die Polizei konfiszierter Drogen und denen, die dann tats\u00e4chlich vorm Richter landen. In New Orleans k\u00f6nnten davon aktuell einige tats\u00e4chlich real sein, denn dort <a href=\"https:\/\/www.spiegel.de\/panorama\/gesellschaft\/new-orleans-ratten-fressen-konfisziertes-marihuana-in-marodem-polizeipraesidium-a-c45dcb2e-3d34-4be9-b046-d06aa86b4702?fbclid=IwAR2kYys0tGSP1PX50MqsnE7oV9icKEK2Tw_-vBqh6jmj6PzlKjNfb6ZY7WQ\">fressen Ratten das Marihuana<\/a> im maroden Polizeipr\u00e4sidium. <\/p>\n<blockquote><p>\u00bbDie Ratten fressen unser Marihuana, sie sind alle high\u00ab, sagte Polizeichefin Anne Kirkpatrick Medienberichten zufolge in einem Gespr\u00e4ch mit Stadtr\u00e4ten. Auf den Schreibtischen in dem seit 1968 von der Beh\u00f6rde genutzten Geb\u00e4ude sei Rattenkot gefunden worden. Au\u00dferdem sei das Geb\u00e4ude von Schimmel und Kakerlaken befallen.<\/p><\/blockquote>\n<p>Der Laden ist so runtergekommen, dass man nun nach einer Alternative dazu sucht. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir alle kennen die Jokes von den Mengen durch die Polizei konfiszierter Drogen und denen, die dann tats\u00e4chlich vorm Richter landen. In New Orleans k\u00f6nnten&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/in-new-orleans-fressen-ratten-konfisziertes-marihuana-in-marodem-polizeipraesidium\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">In New Orleans fressen Ratten konfisziertes Marihuana in marodem Polizeipr\u00e4sidium<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":197908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[1438,488,5235,378,6571],"class_list":["post-197906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alltaglicher-sinnwahn","tag-cannabis","tag-drugs","tag-new-orleans","tag-police","tag-rats","entry"],"jetpack_featured_media_url":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2024\/03\/rat-4075129_1280.jpg","jetpack_shortlink":"https:\/\/wp.me\/pXEnA-Pu2","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/197906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=197906"}],"version-history":[{"count":2,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/197906\/revisions"}],"predecessor-version":[{"id":197910,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/197906\/revisions\/197910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media\/197908"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=197906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=197906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=197906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}