{"id":33885,"date":"2012-02-15T10:16:16","date_gmt":"2012-02-15T09:16:16","guid":{"rendered":"http:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=33885"},"modified":"2012-02-15T10:16:16","modified_gmt":"2012-02-15T09:16:16","slug":"kondomwerbung-mit-marvin-gaye-zwei-plattenspielern-und-bpm-matching","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/kondomwerbung-mit-marvin-gaye-zwei-plattenspielern-und-bpm-matching\/","title":{"rendered":"Kondomwerbung mit Marvin Gaye, zwei Plattenspielern und BPM Matching"},"content":{"rendered":"<p>Grandiose Durex-Werbung, die hier mal rein muss. Zum einen, weil Werbung f\u00fcr Kondome generell nichts Schlechtes sein kann, zum anderen, weil  Plattenspieler bei sind, ein Marvin Gaye Klassiker und weil ziemlich einfach verdeutlicht wird, wie das mit der Geschwindigkeitsanpassung beim Mixen funktioniert.<\/p>\n<p> Mich haben damals immer Leute gefragt, wie das so geht, mit dem Angleichen. Ich erz\u00e4hlte dann immer, dass es wie mit dem Klicken des eigenenen Blinkers an einer roten Ampel sei. Irgendwann n\u00e4mlich liegt dieses synchron auf dem Blinker des vor einem stehenden Autos. Heute w\u00fcrde ich den Clip empfehlen, auch wenn das Angleichen zwei identischer Platten auf Null jetzt auch nicht die Kunst ist. Trotzdem gut.<\/p>\n<p><iframe loading=\"lazy\" width=\"505\" height=\"287\" src=\"http:\/\/www.youtube.com\/embed\/JDAcP4B89iA\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<small>(<a href=\"http:\/\/youtu.be\/JDAcP4B89iA\">Direktlink<\/a>, via <a href=\"http:\/\/www.reddit.com\/r\/videos\/comments\/ppnb8\/genius_condom_advert\/\">reddit<\/a>)<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grandiose Durex-Werbung, die hier mal rein muss. Zum einen, weil Werbung f\u00fcr Kondome generell nichts Schlechtes sein kann, zum anderen, weil Plattenspieler bei sind, ein&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/kondomwerbung-mit-marvin-gaye-zwei-plattenspielern-und-bpm-matching\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Kondomwerbung mit Marvin Gaye, zwei Plattenspielern und BPM Matching<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,8],"tags":[],"class_list":["post-33885","post","type-post","status-publish","format-standard","hentry","category-musik","category-visuelles","entry"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pXEnA-8Ox","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/33885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=33885"}],"version-history":[{"count":0,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/33885\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=33885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=33885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=33885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}