{"id":50717,"date":"2013-03-23T14:27:50","date_gmt":"2013-03-23T13:27:50","guid":{"rendered":"http:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=50717"},"modified":"2013-03-23T15:07:05","modified_gmt":"2013-03-23T14:07:05","slug":"pacos-musikalische-marzzusammenfassung-rot-really-grey","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/pacos-musikalische-marzzusammenfassung-rot-really-grey\/","title":{"rendered":"Pacos musikalische M\u00e4rzzusammenfassung: Not really grey"},"content":{"rendered":"<p><a href=\"http:\/\/risikogruppe.wordpress.com\/2013\/03\/23\/paco-risikogruppe-marz-podcast-not-really-grey\/\">Pacos musikalischer Beitrag f\u00fcr den M\u00e4rz<\/a>. Irgendwo zwischen Winter und Fr\u00fchling. Unter dem Schnee der Asphalt, unter dem Asphalt der Strand. Deephouse aus der ganz tr\u00e4gen Familie, weshalb in Paco auch &#8222;Valium House&#8220; nennt, was auch hier wieder perfekt passt. Gekonnt mixt er sich durch die 90 Minuten in genau der unvorhersehbaren Art un Weise, wie man das von ihm eben gew\u00f6hnt ist. Mein Sound f\u00fcr diesen Samstag.<\/p>\n<p>Und weil Musik immer noch viel sch\u00f6ner ist, wenn einer Geschichten dazu zu erz\u00e4hlen wei\u00df, hat er auch eine.<\/p>\n<blockquote><p>\nweil ich dazumals (2007) gerade f\u00fcr das z\u00fcrcher lethargy festival gebucht wurde und ich mir \u00fcberlegen musste, was ich denn dort ultimativ hippes spielen sollte, verband ich das eine mit dem anderen, und schraubte f\u00fcr mein festivalset ein paar meiner aktuellen lieblingstanzlieder auf 105 bpm runter. ich kann mich noch an die reaktionen einiger erinnern, als ich mein slowmotion set am festival spielte. das unverst\u00e4ndnis der kopfsch\u00fcttelnden, weglaufenden speed-enthusiasten k\u00fcmmerte mich jedoch wenig. mir gefiel diese valiumeske atmosph\u00e4re, dass sich in der halle ausbreitete. und mit mir auch ein paar hundert andere, die sich langsam schwofend darauf einlassen konnten.\n<\/p><\/blockquote>\n<p><iframe loading=\"lazy\" width=\"100%\" height=\"166\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?url=http%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F84101459\"><\/iframe><br \/>\n<small>(<a href=\"https:\/\/soundcloud.com\/risikogruppe\/paco-risikogruppe-not-really-grey\">Direktlink<\/a>)<\/small> <\/p>\n<p><strong>Tracklist:<\/strong><br \/>\nGespleu &#8211; No Prating Angels &#8211; Apollo<br \/>\nDauwd &#8211; And &#8211; Pictures Music<br \/>\nFort Romeau &#8211; Love (Dub) &#8211; Spectral Sound<br \/>\nMano Le Tough &#8211; Moments Of Truth &#8211; Permanent Vacation<br \/>\nMano Le Tough &#8211; Primative People &#8211; Permanent Vacation<br \/>\nKotelett &#038; Zadak &#8211; Jerewan &#8211; KATERMUKKE<br \/>\nSoukie &#038; Windish &#8211; Hero &#8211; URSL<br \/>\nDavid Keno &#038; Nico Stojan &#8211; Princess of the Night (Mira &#038; Chris Schwarzwaelder Remix) &#8211; Voltaire Music<br \/>\nReSketch &#8211; Maybe &#8211; Voltaire Music<br \/>\nMano Le Tough &#8211; Please &#8211; Permanent Vacation<br \/>\nSid Le Rock &#8211; Foreign Love (Acid Pauli Remix) &#8211; My Favorite Robot<br \/>\nYouandewan &#8211; Faith &#8211; 2nd Drop<br \/>\nJonas Woehl &#8211; Breathe (iami Remix) &#8211; City Life<br \/>\nSCSI-9 &#8211; Ellsworth Land &#8211; Renaissance<br \/>\nEmpt &#8211; Far &#8211; Project Mooncircle<br \/>\nLapalux &#8211; Without You (feat. Kerry Leatham) &#8211; Brainfeeder<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pacos musikalischer Beitrag f\u00fcr den M\u00e4rz. Irgendwo zwischen Winter und Fr\u00fchling. Unter dem Schnee der Asphalt, unter dem Asphalt der Strand. Deephouse aus der ganz&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/pacos-musikalische-marzzusammenfassung-rot-really-grey\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Pacos musikalische M\u00e4rzzusammenfassung: Not really grey<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-50717","post","type-post","status-publish","format-standard","hentry","category-musik","entry"],"jetpack_shortlink":"https:\/\/wp.me\/pXEnA-dc1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/50717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=50717"}],"version-history":[{"count":0,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/50717\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=50717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=50717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=50717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}