{"id":5367,"date":"2009-05-07T17:02:29","date_gmt":"2009-05-07T15:02:29","guid":{"rendered":"http:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=5367"},"modified":"2012-11-06T23:46:39","modified_gmt":"2012-11-06T22:46:39","slug":"fotografien-von-berlin-aus-den-60ern","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/fotografien-von-berlin-aus-den-60ern\/","title":{"rendered":"Fotografien von Berlin aus den 60ern"},"content":{"rendered":"<p>Flickr-User allhails hat wirklich zwei sehr beeindruckende Bilderstrecken von Berlin. Eine aus den Jahren <a href=\"http:\/\/www.flickr.com\/photos\/allhails\/sets\/72157603461741786\/\">1959 und 1960<\/a> und ein zweite aus den Jahren <a href=\"http:\/\/www.flickr.com\/photos\/allhails\/sets\/72157604384476181\/\">1962 und 1964<\/a>. w\u00e4hrend er in den Jahren 1959 und 1960 noch eine weitesgehend normal wirkende Stadt portr\u00e4tiert,  hatte er 1962 und 1964 offenbar eine sehr eigene Sicht auf die geteilte Stadt und hat es vermocht, diese auf fast jedem Bild festzuhalten. Enge scheinen diese Bilder zeigen zu wollen, eine sehr enge, sehr statische Stadt. Im Mittelpunkt seiner Arbeiten dann: fast immer die Mauer. <\/p>\n<p>Seine anderen Alben sind \u00fcbrigens auch alle durch die Reihe weg sehenswert. Beeindruckendes Auge hat der Mann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flickr-User allhails hat wirklich zwei sehr beeindruckende Bilderstrecken von Berlin. Eine aus den Jahren 1959 und 1960 und ein zweite aus den Jahren 1962 und&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/fotografien-von-berlin-aus-den-60ern\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Fotografien von Berlin aus den 60ern<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-5367","post","type-post","status-publish","format-standard","hentry","category-visuelles","entry"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pXEnA-1oz","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/5367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=5367"}],"version-history":[{"count":0,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/5367\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=5367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=5367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=5367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}