{"id":61246,"date":"2014-03-11T10:20:41","date_gmt":"2014-03-11T09:20:41","guid":{"rendered":"http:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=61246"},"modified":"2014-03-12T09:29:08","modified_gmt":"2014-03-12T08:29:08","slug":"wenn-sich-sich-wildfremde-zum-knutschen-treffen-first-kiss","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wenn-sich-sich-wildfremde-zum-knutschen-treffen-first-kiss\/","title":{"rendered":"Wenn sich sich wildfremde zum Knutschen treffen: First Kiss"},"content":{"rendered":"<p>Die Filmemacherin <a href=\"https:\/\/www.youtube.com\/channel\/UCBkHxU4e4bT_q5UxhYfsGjQ?feature=watch\">Tatia Pilieva<\/a> hat 20 Menschen in ein Studio eingeladen, die sich vorher nicht kannten. Diese konnten sich dann dort gegenseitig knutschen, so denn sie wollten.  Das klingt erst mal viel einfacher, als es am Ende dann doch Zutrauen braucht.  Eis brechen und so. Die Menschen knutschen ja generell viel zu wenig.<\/p>\n<p><strong>[Update]<\/strong> Mittlerweile als ein Werbeclip f\u00fcr ein Modelabel identifiziert, was ihn immerhin noch zu einem gelungenen Filmchen macht.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/IpbDHxCV29A?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=de-DE&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><br \/>\n<small>(<a href=\"http:\/\/youtu.be\/IpbDHxCV29A\">Direktlink<\/a>, via <a href=\"http:\/\/www.likecool.com\/First_Kiss--Video--Gear.html\">Like Cool<\/a>)<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Filmemacherin Tatia Pilieva hat 20 Menschen in ein Studio eingeladen, die sich vorher nicht kannten. Diese konnten sich dann dort gegenseitig knutschen, so denn&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wenn-sich-sich-wildfremde-zum-knutschen-treffen-first-kiss\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Wenn sich sich wildfremde zum Knutschen treffen: First Kiss<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":61247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[255,1738],"class_list":["post-61246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visuelles","tag-kisses","tag-tatia-pilieva","entry"],"jetpack_shortlink":"https:\/\/wp.me\/pXEnA-fVQ","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/03\/Bildschirmfoto-2014-03-11-um-10.09.34.png","_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/61246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=61246"}],"version-history":[{"count":3,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/61246\/revisions"}],"predecessor-version":[{"id":61317,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/61246\/revisions\/61317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media\/61247"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=61246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=61246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=61246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}