{"id":73386,"date":"2014-09-13T22:21:03","date_gmt":"2014-09-13T20:21:03","guid":{"rendered":"http:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=73386"},"modified":"2014-09-22T19:57:43","modified_gmt":"2014-09-22T17:57:43","slug":"ni-traktor-s8-dj-controller","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/ni-traktor-s8-dj-controller\/","title":{"rendered":"NI Traktor S8 DJ Controller?"},"content":{"rendered":"<a href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/traktor-s8-teaser-1070x430.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/traktor-s8-teaser-1070x430.jpg\" alt=\"traktor-s8-teaser-1070x430\" width=\"1070\" height=\"430\" class=\"alignnone size-full wp-image-73389\" srcset=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/traktor-s8-teaser-1070x430.jpg 1070w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/traktor-s8-teaser-1070x430-300x120.jpg 300w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/traktor-s8-teaser-1070x430-600x241.jpg 600w\" sizes=\"auto, (max-width: 1070px) 100vw, 1070px\" \/><\/a>\n<p>Auf Amazon gab es die Tage f\u00fcr kurz einen Traktor Controller, den es so noch gar nicht gibt. Keine Ahnung, wie genau der dort hinkam. Entweder \u00fcbt man sich bei Native gerade im viralen Marketing, hat ein-zwei H\u00e4kchen beim Publishen vergessen, oder irgendwer verbindet seine Photoshop-Skillz mit seinen Ideen f\u00fcr _den_ Controller schlechthin.<\/p>\n<a href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/Native-Instruments-Traktor-Kontrol-S8-DJ-Controller-rblln-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/Native-Instruments-Traktor-Kontrol-S8-DJ-Controller-rblln-1-600x666.jpg\" alt=\"Native-Instruments-Traktor-Kontrol-S8-DJ-Controller-rblln-1\" width=\"600\" height=\"666\" class=\"alignnone size-large wp-image-73388\" srcset=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/Native-Instruments-Traktor-Kontrol-S8-DJ-Controller-rblln-1-600x666.jpg 600w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/Native-Instruments-Traktor-Kontrol-S8-DJ-Controller-rblln-1-269x300.jpg 269w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><p><br \/>\n<small>(<a href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/Native-Instruments-Traktor-Kontrol-S8-DJ-Controller-rblln-1.jpg\">Klick<\/a> f\u00fcr in gro\u00df)<\/small><\/p>\n<p>Mittlerweile wurde der Artikel wieder gel\u00f6scht, auch der Google Cache gibt nichts mehr her. Soweit, so gut. <\/p>\n<p>Was allerdings sofort ins Auge f\u00e4llt: Die Jog Wheels fehlen. Und ich mag Controller ohne Jog Wheels nicht sonderlich. Da bin dann selbst ich eher konservativ. So viel Haptik darf es dann doch schon sein, wie ich letzte Nacht erst wieder feststellte, als ich mit Vinyl und Controller mixte. Dieses Petting-Geschiebe, welches hier per Touch-Strips angezeigt wird, fetzt nicht wirklich. Fetzte schon beim <a href=\"http:\/\/www.vintagesynth.com\/moog\/micromoog.php\">Micromoog<\/a> nicht und der ist seit mindestens 20 Jahren Geschichte. <\/p>\n<p>Controller-Walter hat das Dingen anhand seiner aktuellen Darstellung <a href=\"http:\/\/www.blogrebellen.de\/2014\/09\/13\/traktor-s8-dj-controller\/\">mal auseinander genommen<\/a>. <\/p>\n<blockquote><p>Der Controller wirkt wie ein durchdachtes Mashup der Produkte aus der Native Instruments Produktreihe. Sozusagen verbaut ist eine komplette S4 in Kombination mit zwei Kontrol F1. Hinzu kommen zwei Displays, die im Produktbild sowohl eine Player-Waveform-Ansicht, als auch einen View f\u00fcr die Remix-Decks bieten.<\/p>\n<p>Auf die Scrollr\u00e4der wurde verzichtet, daf\u00fcr sind zwei Touch-Sprips verbaut, die man vom Kontrol X1 kennt. Der Aufbau der Remix-Sektion mit acht Pads auf jeder Seite und jeweils vier Fadern  erinnern stark an die F1.<br \/>\nAu\u00dfen, neben den Pads sieht man die Tasten Loop, Freeze, Hotcue und Remix, Schnellzuordnungen, die man von Serato-Controllern kennt.<\/p>\n<p>Wie schon bei der S4 bekommt jeder Channel-Fader einen eigenen Peakmeter, die allerdings neben der EQ-Section positioniert sind, was meiner Meinung nach auch ein besserer Platz daf\u00fcr ist. Die LED-Ketten sind im Vergleich zur S4 feiner aufgel\u00f6st. Bei den Fadern f\u00e4llt auf, dass der komplette Bereich mit Schrauben befestigt ist. Die Sektion scheint austauschbar zu sein.<\/p><\/blockquote>\n<p>Es zeigt ganz klar integrierte Displays, die Waveformen k\u00f6nnen.  Walter meint, daf\u00fcr m\u00fcsste es einen USB-Anschluss geben. Dann w\u00e4re die Kiste frei von jeglichen Peripherie-Ger\u00e4ten wie einem Rechner, der daf\u00fcr angeschlossen werden m\u00fcsste. Was er nicht bedenkt ist die M\u00f6glichkeit, sich die Files auch per WLAN oder Bluetooth zu holen. W\u00e4re dann immer noch nicht Stand Alone, aber immerhin frei von Verkabelung. Und trotzdem ohne Jog Wheels. So werden wir keine Partner, Native. Wenn das \u00fcberhaupt alles irgendwie so kommen sollte. Denn das wei\u00df man ja aktuell auch gar nicht so genau. Aber geil aussehen tut die Kiste schon, ja. Der Prei l\u00e4ge hiernach bei $1200, woran man sich wohl gew\u00f6hnen werden muss. Die rechnen halt schon alle mit Hinblick auf &#8222;Was w\u00fcrden zwei 1210er + gutem 2-Kanal Mixer kosten?&#8220;. Pioneer hatte diesbez\u00fcglich den Preis daf\u00fcr ja schon vorgelegt. <\/p>\n<a href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/91KYtClNCFL._SL1500_-670x433.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/91KYtClNCFL._SL1500_-670x433.jpg\" alt=\"91KYtClNCFL._SL1500_-670x433\" width=\"670\" height=\"433\" class=\"alignnone size-full wp-image-73391\" srcset=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/91KYtClNCFL._SL1500_-670x433.jpg 670w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/91KYtClNCFL._SL1500_-670x433-300x193.jpg 300w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2014\/09\/91KYtClNCFL._SL1500_-670x433-600x387.jpg 600w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/a>\n<p>Warten wir es also einfach mal ab. Irgendwas in dieser Richtung wird auf jeden Fall kommen, egal ob das hier echt oder ein wirklich guter Fake ist. Ich hoffe derweil, dass die Variante mit den Jog Wheels nicht aussterben wird. So.<br \/>\n<small>(via <a href=\"http:\/\/www.blogrebellen.de\/2014\/09\/13\/traktor-s8-dj-controller\/\">Blogrebellen<\/a>)<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf Amazon gab es die Tage f\u00fcr kurz einen Traktor Controller, den es so noch gar nicht gibt. Keine Ahnung, wie genau der dort hinkam.&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/ni-traktor-s8-dj-controller\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">NI Traktor S8 DJ Controller?<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[2850,2606,2849,336],"class_list":["post-73386","post","type-post","status-publish","format-standard","hentry","category-musik","tag-controller","tag-djism","tag-native-instruments","tag-traktor","entry"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pXEnA-j5E","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/73386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=73386"}],"version-history":[{"count":12,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/73386\/revisions"}],"predecessor-version":[{"id":73917,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/73386\/revisions\/73917"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=73386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=73386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=73386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}