{"id":89544,"date":"2015-05-22T17:51:28","date_gmt":"2015-05-22T15:51:28","guid":{"rendered":"http:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=89544"},"modified":"2015-05-22T17:51:28","modified_gmt":"2015-05-22T15:51:28","slug":"supermaerkte-in-frankreich-muessen-nicht-verkaufte-lebensmittel-spenden","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/supermaerkte-in-frankreich-muessen-nicht-verkaufte-lebensmittel-spenden\/","title":{"rendered":"Superm\u00e4rkte in Frankreich m\u00fcssen nicht verkaufte Lebensmittel spenden"},"content":{"rendered":"<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2015\/05\/2856039679_71007c74f7_z.jpg\" alt=\"2856039679_71007c74f7_z\" width=\"640\" height=\"480\" class=\"alignnone size-full wp-image-89545\" srcset=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2015\/05\/2856039679_71007c74f7_z.jpg 640w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2015\/05\/2856039679_71007c74f7_z-300x225.jpg 300w, https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2015\/05\/2856039679_71007c74f7_z-600x450.jpg 600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><p><br \/>\n<small>(Foto: <a href=\"https:\/\/flic.kr\/p\/5mnX6r\">Jeremy Keith<\/a>, CC BY 2.0)<\/small><\/p>\n<p>Hierzulande werden j\u00e4hrlich Tonnen von Nahrungsmitteln weggeworfen, die eigentlich noch gut essbar sind. Das ist offenbar in Frankreich nicht anders und so werden dort nun Superm\u00e4rkte, die gr\u00f6\u00dfer als 400 Quadratmeter sind, dazu verpflichtet, <a href=\"http:\/\/www.sueddeutsche.de\/politik\/frankreich-supermaerkte-muessen-nicht-verkaufte-lebensmittel-spenden-1.2490126\">ihre nicht verkauften Nahrungsmittel an karitative Einrichtungen zu spenden<\/a> oder als Tierfutter oder Kompost zu recyceln.<\/p>\n<blockquote><p>Die franz\u00f6sische Nationalversammlung hat einstimmig entschieden, dass gro\u00dfe Superm\u00e4rkte k\u00fcnftig nicht verkaufte Lebensmittel nicht mehr wegwerfen d\u00fcrfen. Die Abgeordneten haben der Verabschiedung von drei Zusatzartikeln zu einem bereits bestehenden Gesetz zugestimmt.<\/p>\n<p>Die Regierung m\u00f6chte die Verschwendung von Lebensmitteln bis 2025 halbieren. Ob der Vorsto\u00df des Parlaments in bedeutsamen Ma\u00dfe dazu beitr\u00e4gt, ist allerdings umstritten. In Frankreich stammen nur f\u00fcnf Prozent der Lebensmittelabf\u00e4lle von den gro\u00dfen Handelsketten. Dagegen wirft jeder Franzose pro Jahr zwanzig bis drei\u00dfig Kilo Essen weg.<\/p><\/blockquote>\n<p>Find ich gut. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Foto: Jeremy Keith, CC BY 2.0) Hierzulande werden j\u00e4hrlich Tonnen von Nahrungsmitteln weggeworfen, die eigentlich noch gut essbar sind. Das ist offenbar in Frankreich nicht&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/supermaerkte-in-frankreich-muessen-nicht-verkaufte-lebensmittel-spenden\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Superm\u00e4rkte in Frankreich m\u00fcssen nicht verkaufte Lebensmittel spenden<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[1208,439,2376],"class_list":["post-89544","post","type-post","status-publish","format-standard","hentry","category-nur-mal-so","tag-capitalism","tag-food","tag-france","entry"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pXEnA-nig","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/89544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=89544"}],"version-history":[{"count":2,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/89544\/revisions"}],"predecessor-version":[{"id":89547,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/89544\/revisions\/89547"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=89544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=89544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=89544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}