{"id":92787,"date":"2015-08-09T14:29:18","date_gmt":"2015-08-09T12:29:18","guid":{"rendered":"http:\/\/www.kraftfuttermischwerk.de\/blogg\/?p=92787"},"modified":"2015-08-09T14:29:18","modified_gmt":"2015-08-09T12:29:18","slug":"hydranten-fontaene-in-charlottenburg","status":"publish","type":"post","link":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/hydranten-fontaene-in-charlottenburg\/","title":{"rendered":"Hydranten-Font\u00e4ne in Charlottenburg"},"content":{"rendered":"<p>F\u00fcr etwas Abk\u00fchlung sorgte gestern offenbar ein B\u00fcrger in Berlin Charlottenburg, in dem er einfach einen Hydranten aufschraubte, so dass das k\u00fchlende Nass f\u00fcr kurze Zeit auf die Krumme Stra\u00dfe prasselte.  Klimatisch bedingte Notwehr. Oder so. <\/p>\n<blockquote><p>In der Krummen Stra\u00dfe in Charlottenburg hat sich offenbar jemand ganz doll eine Abk\u00fchlung gew\u00fcnscht &#8211; und einen Hydranten ge\u00f6ffnet. Die Feuerwehr geht jedenfalls nicht von einem technischen Defekt aus. Auch das Technische Hilfswerk eilte herbei und nach gut einer Stunde war die riesige Font\u00e4ne dann wieder verschwunden.<\/p><\/blockquote>\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/abendschau.rbb\/videos\/vb.141018599260302\/1085215824840570\/?type=2&amp;theater\" data-width=\"600\">\n<div class=\"fb-xfbml-parse-ignore\">\n<blockquote cite=\"https:\/\/www.facebook.com\/abendschau.rbb\/videos\/1085215824840570\/\">\n<p>In der Krummen Stra&#xdf;e in Charlottenburg hat sich offenbar jemand ganz doll eine Abk&#xfc;hlung gew&#xfc;nscht &#8211; und einen&#8230;<\/p>\n<p>Posted by <a href=\"https:\/\/www.facebook.com\/abendschau.rbb\">Abendschau<\/a> on&nbsp;<a href=\"https:\/\/www.facebook.com\/abendschau.rbb\/videos\/1085215824840570\/\">Samstag, 8. August 2015<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p><\/br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr etwas Abk\u00fchlung sorgte gestern offenbar ein B\u00fcrger in Berlin Charlottenburg, in dem er einfach einen Hydranten aufschraubte, so dass das k\u00fchlende Nass f\u00fcr kurze&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.kraftfuttermischwerk.de\/blogg\/hydranten-fontaene-in-charlottenburg\/\">Mehr lesen -&gt;<span class=\"screen-reader-text\">Hydranten-Font\u00e4ne in Charlottenburg<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":92789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[82,1459,2312,1535],"class_list":["post-92787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nur-mal-so","tag-berlin","tag-summer","tag-water","tag-weather","entry"],"jetpack_featured_media_url":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-content\/uploads2\/2015\/08\/Bildschirmfoto-2015-08-09-um-14.28.45.png","jetpack_shortlink":"https:\/\/wp.me\/pXEnA-o8z","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/92787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/comments?post=92787"}],"version-history":[{"count":3,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/92787\/revisions"}],"predecessor-version":[{"id":92791,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/posts\/92787\/revisions\/92791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media\/92789"}],"wp:attachment":[{"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/media?parent=92787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/categories?post=92787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraftfuttermischwerk.de\/blogg\/wp-json\/wp\/v2\/tags?post=92787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}